{"id":225,"date":"2023-11-15T18:36:20","date_gmt":"2023-11-15T18:36:20","guid":{"rendered":"https:\/\/smjatcsd.org\/?page_id=225"},"modified":"2024-01-26T00:32:37","modified_gmt":"2024-01-26T00:32:37","slug":"application","status":"publish","type":"page","link":"https:\/\/smjatcsd.org\/es\/application\/","title":{"rendered":"Aplicaci\u00f3n"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"225\" class=\"elementor elementor-225\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ea231b5 e-flex e-con-boxed e-con e-parent\" data-id=\"ea231b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d61c979 elementor-widget elementor-widget-heading\" data-id=\"d61c979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aplicaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87cfeba elementor-widget elementor-widget-text-editor\" data-id=\"87cfeba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<script type=\"text\/javascript\" src=\"https:\/\/www.totaltrack.org\/Scripts\/jquery-1.11.0.min.js\"><\/script>\n\n<script type=\"text\/javascript\" src=\"https:\/\/www.totaltrack.org\/Scripts\/jquery.validate.js\"><\/script>\n\n<form class=\"totaltrack\" action=\"https:\/\/www.totaltrack.org\/Api\/EducationApi\/SubmitApplication\" method=\"post\">\n<fieldset><legend>Info:<\/legend><!-- You may change the layout and arrangment of these fields, but the name attributes on each input\/select must remain the same. -->\n\n<label for=\"prefix\">Prefijo:<\/label><input id=\"prefix\" class=\"\" title=\"Prefijo\" maxlength=\"255\" name=\"prefix\" type=\"text\" value=\"\" \/>\n\n<label for=\"firstName\">Nombre:*<\/label><input id=\"firstName\" class=\"required\" title=\"Nombre\" maxlength=\"255\" name=\"firstName\" type=\"text\" value=\"\" \/>\n\n<label for=\"middleName\">Segundo nombre:<\/label><input id=\"middleName\" class=\"\" title=\"Segundo nombre\" maxlength=\"255\" name=\"middleName\" type=\"text\" value=\"\" \/>\n\n<label for=\"lastName\">Apellido:*<\/label><input id=\"lastName\" class=\"required\" title=\"Apellido\" maxlength=\"255\" name=\"lastName\" type=\"text\" value=\"\" \/>\n\n<label for=\"suffix\">Sufijo:<\/label><input id=\"suffix\" class=\"\" title=\"Sufijo\" maxlength=\"255\" name=\"suffix\" type=\"text\" value=\"\" \/>\n\n<label for=\"dateOfBirth\">Fecha de nacimiento<\/label><input id=\"dateOfBirth\" class=\"date required\" title=\"Fecha de nacimiento\" maxlength=\"255\" name=\"dateOfBirth\" type=\"text\" value=\"\" \/>\n\n<label for=\"ssn\">SSN:*<\/label><input id=\"ssn\" class=\"ssn required\" title=\"SSN\" maxlength=\"255\" name=\"ssn\" type=\"text\" value=\"\" \/>\n\n<label for=\"gender\">G\u00e9nero:<\/label><select id=\"gender\" class=\"\" name=\"gender\">\n<option value=\"0\"><\/option>\n<option value=\"1\">Hombre<\/option>\n<option value=\"2\">Mujer<\/option>\n<\/select>\n\n<label for=\"ethnicity\">Etnia:*<\/label><select id=\"ethnicity\" class=\"required\" name=\"ethnicity\">\n<option value=\"337\">Indio americano o nativo de Alaska<\/option>\n<option value=\"338\">Asi\u00e1tico<\/option>\n<option value=\"598841\">Indio asi\u00e1tico<\/option>\n<option value=\"598842\">Bangladesh<\/option>\n<option value=\"339\">Negro o afroamericano<\/option>\n<option value=\"598844\">Camboya<\/option>\n<option value=\"598843\">Chino<\/option>\n<option value=\"598857\">Fiyi<\/option>\n<option value=\"598845\">Filipino<\/option>\n<option value=\"598858\">Guam\u00e1n<\/option>\n<option value=\"598859\">Hawaiano<\/option>\n<option value=\"336\">Hispano o latino<\/option>\n<option value=\"598846\">Hmong<\/option>\n<option value=\"598847\">Indonesia<\/option>\n<option value=\"598848\">Japon\u00e9s<\/option>\n<option value=\"598849\">Coreano<\/option>\n<option value=\"598850\">Laos<\/option>\n<option value=\"598851\">Malasia<\/option>\n<option value=\"340\">Nativo de Hawai u otras islas del Pac\u00edfico<\/option>\n<option value=\"598852\">Pakist\u00e1n<\/option>\n<option value=\"598860\">Samoa<\/option>\n<option value=\"598853\">Sri Lanka<\/option>\n<option value=\"598854\">Taiw\u00e1n<\/option>\n<option value=\"598855\">Tailand\u00e9s<\/option>\n<option value=\"598861\">Tonga<\/option>\n<option value=\"598856\">Vietnamita<\/option>\n<option value=\"341\">Blanco<\/option>\n<\/select>\n\n<label for=\"veteran\">Veterano:<\/label><select id=\"veteran\" class=\"\" name=\"veteran\">\n<option value=\"0\"><\/option>\n<option value=\"True\">S\u00ed<\/option>\n<option value=\"False\">No<\/option>\n<\/select>\n\n<label for=\"street\">Calle:*<\/label><input id=\"street\" class=\"required\" title=\"Calle\" maxlength=\"255\" name=\"street\" type=\"text\" value=\"\" \/>\n\n<label for=\"city\">Ciudad:*<\/label><input id=\"city\" class=\"required\" title=\"Ciudad\" maxlength=\"255\" name=\"city\" type=\"text\" value=\"\" \/>\n\n<label for=\"state\">Estado:*<\/label><input id=\"state\" class=\"state required\" title=\"Estado\" maxlength=\"255\" name=\"state\" type=\"text\" value=\"\" \/>\n\n<label for=\"zipCode\">C\u00f3digo postal<\/label><input id=\"zipCode\" class=\"zip required\" title=\"C\u00f3digo postal\" maxlength=\"255\" name=\"zipCode\" type=\"text\" value=\"\" \/>\n\n<label for=\"addressType\">Tipo de direcci\u00f3n:*<\/label><select id=\"addressType\" class=\"required\" name=\"addressType\">\n<option value=\"16\">Empresas<\/option>\n<option value=\"17\">Inicio<\/option>\n<\/select>\n\n<label for=\"phone1\">N\u00famero de tel\u00e9fono principal:*<\/label><input id=\"phone1\" class=\"phone required\" title=\"N\u00famero de tel\u00e9fono principal\" maxlength=\"255\" name=\"phone1\" type=\"text\" value=\"\" \/>\n\n<label for=\"phoneType1\">Tipo de tel\u00e9fono principal:*<\/label><select id=\"phoneType1\" class=\"required\" name=\"phoneType1\">\n<option value=\"20\">Celda<\/option>\n<option value=\"21\">Fax<\/option>\n<option value=\"18\">Inicio<\/option>\n<option value=\"597850\">Oficina<\/option>\n<option value=\"31257001\">Otros<\/option>\n<option value=\"22\">Buscapersonas<\/option>\n<option value=\"19\">Trabajo<\/option>\n<\/select>\n\n<label for=\"email\">Correo electr\u00f3nico:*<\/label><input id=\"email\" class=\"required\" title=\"Correo electr\u00f3nico\" maxlength=\"255\" name=\"email\" type=\"text\" value=\"\" \/>\n\n<label for=\"emailAddressType\">Tipo de direcci\u00f3n de correo electr\u00f3nico:*<\/label><select id=\"emailAddressType\" class=\"required\" name=\"emailAddressType\">\n<option value=\"13\">Inicio<\/option>\n<option value=\"15\">PDA<\/option>\n<option value=\"14\">Trabajo<\/option>\n<\/select><\/fieldset>\n<fieldset><legend>Respuestas:<\/legend>\n<div><\/div>\n<div id=\"section2781\" class=\"category quiz instructionsRoot\">\n\nSOLICITUD PARA EL APRENDIZAJE DE CHAPA LOCAL 206\n\n<\/div>\n<div class=\"group quiz\">\n<div class=\"question\" style=\"page-break-inside: avoid;\">\n\n<label class=\"instructionsRoot\" for=\"_lt1\">\u00bfC\u00f3mo conoci\u00f3 este programa?<\/label>\n<div class=\"hiddentextareatext\"><\/div>\n<textarea class=\"required\" cols=\"20\" name=\"_lt1\" rows=\"2\"><\/textarea>\n\n<\/div>\n<div class=\"question\" style=\"page-break-inside: avoid;\">\n\n<label class=\"instructionsRoot\" for=\"_st1\">Firma*<\/label><input class=\"required\" autocomplete=\"off\" maxlength=\"125\" name=\"_st1\" type=\"text\" value=\"\" \/>\n\n<\/div>\n<\/div><\/fieldset>\n<div class=\"errors\"><\/div>\n<input class=\"sub\" type=\"submit\" value=\"Enviar solicitud\" \/>\n\n<input name=\"applicationGuid\" type=\"hidden\" value=\"b8589203-5d41-4dbd-8eb4-9e9d623d840c\" \/>\n\n<\/form>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Application Info: Prefix: First name:* Middle name: Last name:* Suffix: Date of birth:* SSN:* Gender:MaleFemale Ethnicity:*American Indian or Alaska NativeAsianAsian IndianBangladeshiBlack or African AmericanCambodianChineseFijianFilipinoGuamanianHawaiianHispanic or LatinoHmongIndonesianJapaneseKoreanLaotianMalaysianNative Hawaiian or Other Pacific IslanderPakistaniSamoanSri LankanTaiwaneseThaiTonganVietnameseWhite Veteran:YesNo Street:* City:* State:* Zip code:* Address type:*BusinessHome Primary phone number:* Primary phone type:*CellFaxHomeOfficeOtherPagerWork Email:* Email address type:*HomePDAWork Answers: APPLICATION FOR LOCAL 206 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2899,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-225","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Application - SHEET METAL JATC SAN DIEGO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smjatcsd.org\/es\/application\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Application - SHEET METAL JATC SAN DIEGO\" \/>\n<meta property=\"og:description\" content=\"Application Info: Prefix: First name:* Middle name: Last name:* Suffix: Date of birth:* SSN:* Gender:MaleFemale Ethnicity:*American Indian or Alaska NativeAsianAsian IndianBangladeshiBlack or African AmericanCambodianChineseFijianFilipinoGuamanianHawaiianHispanic or LatinoHmongIndonesianJapaneseKoreanLaotianMalaysianNative Hawaiian or Other Pacific IslanderPakistaniSamoanSri LankanTaiwaneseThaiTonganVietnameseWhite Veteran:YesNo Street:* City:* State:* Zip code:* Address type:*BusinessHome Primary phone number:* Primary phone type:*CellFaxHomeOfficeOtherPagerWork Email:* Email address type:*HomePDAWork Answers: APPLICATION FOR LOCAL 206 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smjatcsd.org\/es\/application\/\" \/>\n<meta property=\"og:site_name\" content=\"SHEET METAL JATC SAN DIEGO\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-26T00:32:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smjatcsd.org\/wp-content\/uploads\/2024\/01\/Cover-Image.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/\",\"url\":\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/\",\"name\":\"Application - SHEET METAL JATC SAN DIEGO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smjatcsd.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Cover-Image.webp\",\"datePublished\":\"2023-11-15T18:36:20+00:00\",\"dateModified\":\"2024-01-26T00:32:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smjatcsd.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Cover-Image.webp\",\"contentUrl\":\"https:\\\/\\\/smjatcsd.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Cover-Image.webp\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/es\\\/application\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smjatcsd.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Application\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/#website\",\"url\":\"https:\\\/\\\/smjatcsd.org\\\/\",\"name\":\"SHEET METAL JATC SAN DIEGO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smjatcsd.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/#organization\",\"name\":\"SHEET METAL JATC SAN DIEGO\",\"url\":\"https:\\\/\\\/smjatcsd.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smjatcsd.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-Horizontal_Blue.webp\",\"contentUrl\":\"https:\\\/\\\/smjatcsd.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-Horizontal_Blue.webp\",\"width\":925,\"height\":245,\"caption\":\"SHEET METAL JATC SAN DIEGO\"},\"image\":{\"@id\":\"https:\\\/\\\/smjatcsd.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aplicaci\u00f3n - SHEET METAL JATC SAN DIEGO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smjatcsd.org\/es\/application\/","og_locale":"es_MX","og_type":"article","og_title":"Application - SHEET METAL JATC SAN DIEGO","og_description":"Application Info: Prefix: First name:* Middle name: Last name:* Suffix: Date of birth:* SSN:* Gender:MaleFemale Ethnicity:*American Indian or Alaska NativeAsianAsian IndianBangladeshiBlack or African AmericanCambodianChineseFijianFilipinoGuamanianHawaiianHispanic or LatinoHmongIndonesianJapaneseKoreanLaotianMalaysianNative Hawaiian or Other Pacific IslanderPakistaniSamoanSri LankanTaiwaneseThaiTonganVietnameseWhite Veteran:YesNo Street:* City:* State:* Zip code:* Address type:*BusinessHome Primary phone number:* Primary phone type:*CellFaxHomeOfficeOtherPagerWork Email:* Email address type:*HomePDAWork Answers: APPLICATION FOR LOCAL 206 [&hellip;]","og_url":"https:\/\/smjatcsd.org\/es\/application\/","og_site_name":"SHEET METAL JATC SAN DIEGO","article_modified_time":"2024-01-26T00:32:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/smjatcsd.org\/wp-content\/uploads\/2024\/01\/Cover-Image.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smjatcsd.org\/es\/application\/","url":"https:\/\/smjatcsd.org\/es\/application\/","name":"Aplicaci\u00f3n - SHEET METAL JATC SAN DIEGO","isPartOf":{"@id":"https:\/\/smjatcsd.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smjatcsd.org\/es\/application\/#primaryimage"},"image":{"@id":"https:\/\/smjatcsd.org\/es\/application\/#primaryimage"},"thumbnailUrl":"https:\/\/smjatcsd.org\/wp-content\/uploads\/2024\/01\/Cover-Image.webp","datePublished":"2023-11-15T18:36:20+00:00","dateModified":"2024-01-26T00:32:37+00:00","breadcrumb":{"@id":"https:\/\/smjatcsd.org\/es\/application\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smjatcsd.org\/es\/application\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/smjatcsd.org\/es\/application\/#primaryimage","url":"https:\/\/smjatcsd.org\/wp-content\/uploads\/2024\/01\/Cover-Image.webp","contentUrl":"https:\/\/smjatcsd.org\/wp-content\/uploads\/2024\/01\/Cover-Image.webp","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/smjatcsd.org\/es\/application\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smjatcsd.org\/"},{"@type":"ListItem","position":2,"name":"Application"}]},{"@type":"WebSite","@id":"https:\/\/smjatcsd.org\/#website","url":"https:\/\/smjatcsd.org\/","name":"CHAPA JATC SAN DIEGO","description":"","publisher":{"@id":"https:\/\/smjatcsd.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smjatcsd.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/smjatcsd.org\/#organization","name":"CHAPA JATC SAN DIEGO","url":"https:\/\/smjatcsd.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/smjatcsd.org\/#\/schema\/logo\/image\/","url":"https:\/\/smjatcsd.org\/wp-content\/uploads\/2023\/11\/cropped-Horizontal_Blue.webp","contentUrl":"https:\/\/smjatcsd.org\/wp-content\/uploads\/2023\/11\/cropped-Horizontal_Blue.webp","width":925,"height":245,"caption":"SHEET METAL JATC SAN DIEGO"},"image":{"@id":"https:\/\/smjatcsd.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/pages\/225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/comments?post=225"}],"version-history":[{"count":28,"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/pages\/225\/revisions"}],"predecessor-version":[{"id":2754,"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/pages\/225\/revisions\/2754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/media\/2899"}],"wp:attachment":[{"href":"https:\/\/smjatcsd.org\/es\/wp-json\/wp\/v2\/media?parent=225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}